{"id":368,"date":"2016-09-19T09:41:26","date_gmt":"2016-09-19T12:41:26","guid":{"rendered":"https:\/\/www.doutorpet.com\/blog\/?p=368"},"modified":"2021-02-18T15:15:06","modified_gmt":"2021-02-18T18:15:06","slug":"entenda-a-diferenca-das-vacinas-v8-e-v10","status":"publish","type":"post","link":"https:\/\/blog.doutorpet.com\/blog\/entenda-a-diferenca-das-vacinas-v8-e-v10\/","title":{"rendered":"Entenda a diferen\u00e7a das vacinas V8 e V10"},"content":{"rendered":"<p style=\"text-align: left;\">As vacinas de V8 e V10, devem ser tomadas em torno de 60 dias de vida do animal, com intervalo de 25 dias entre uma dose e outra.<\/p>\n<p style=\"text-align: left;\">A partir dos 45 dias, o animal pode ser imunizado pela primeira vez. Nas primeiras doses das vacinas V8 e V10, s\u00e3o dadas em 3 \u201cparcelas\u201d, chamadas de refor\u00e7o.<\/p>\n<p style=\"text-align: left;\">A da <a href=\"http:\/\/www.doutorpet.com\/blog\/gripe-canina-sintomas-vacina-e-tratamento\" target=\"_blank\" rel=\"noopener noreferrer\">gripe canina<\/a> e raiva n\u00e3o \u00e9 necess\u00e1rio o refor\u00e7o, apenas manuten\u00e7\u00f5es anuais. \u00c9 importante n\u00e3o esquecer nenhuma das vacinas, pois podem perder a efic\u00e1cia e seu pet pode contrair alguma doen\u00e7a em que estava imunizado antes.<\/p>\n<h2 style=\"text-align: left;\">A diferen\u00e7a entre V8 e V10<\/h2>\n<p style=\"text-align: left;\">A diferen\u00e7a \u00e9 que existem 4 tipos de Leptospirose, para cada tipo existe um ant\u00edgeno espec\u00edfico. Ambas as vacinas protegem o pet contra 7 doen\u00e7as, mas a V8 protege contra a Leptospira Canicola e a Leptospira Icterohahemorrhagiae, enquanto a V10 inclui os ant\u00edgenos para Leptospira Grippotyphosa e Leptospira Pomona.<\/p>\n<p style=\"text-align: left;\">Veja abaixo, algumas doen\u00e7as que as vacinas previnem:<\/p>\n<h3 style=\"text-align: left;\">Cinomose<\/h3>\n<p style=\"text-align: left;\">Afeta os filhotes at\u00e9 um ano de vida. \u00c9 sist\u00eamica, ou seja, pode atingir v\u00e1rios \u00f3rg\u00e3os. A doen\u00e7a \u00e9 viral e pode ser passada de um animal para outro n\u00e3o imunizado. Os sintomas s\u00e3o: perda de apetite, corrimento ocular e nasal, diarreia, v\u00f4mito, convuls\u00f5es e pode ir a \u00f3bito.<\/p>\n<h3 style=\"text-align: left;\">Hepatite infecciosa canina<\/h3>\n<p style=\"text-align: left;\">\u00c9 transmitida para o c\u00e3o por meio de secre\u00e7\u00f5es, excrementos e sangue infectado pelo adenov\u00edrus. Os sintomas s\u00e3o febre, dor abdominal, v\u00f4mitos, ataques convulsivos, depress\u00e3o e coma.<\/p>\n<h3 style=\"text-align: left;\">Adenovirose<\/h3>\n<p style=\"text-align: left;\">Afeta o sistema respirat\u00f3rio, dando abertura para a entrada de outras doen\u00e7as mais graves.<\/p>\n<h3 style=\"text-align: left;\">Coronavirose<\/h3>\n<p style=\"text-align: left;\">\u00c9 encontrado nas fezes nos animais infectados. Os sintomas s\u00e3o crises de v\u00f4mito e diarreia, febre, fezes com sangue, depress\u00e3o, perda de apetite e desidrata\u00e7\u00e3o. Pode levar o animal a \u00f3bito.<\/p>\n<h3 style=\"text-align: left;\">Parainfluenza canina<\/h3>\n<p style=\"text-align: left;\">\u00c9 transmitida pelo contato direto com um animal infectado e outro sadio. Os sintomas s\u00e3o tosses graves, secre\u00e7\u00f5es, febre e coriza, al\u00e9m de debilitar o corpo do animal.<\/p>\n<h3 style=\"text-align: left;\">Parvovirose<\/h3>\n<p style=\"text-align: left;\">Uma das doen\u00e7as mais letais em <a href=\"https:\/\/www.doutorpet.com\/blog\/?s=filhotes\">filhotes<\/a>. \u00c9 transmitida pelo contado de fezes de um animal infectado com um sadio. Pode ocorrer morte s\u00fabita em filhotes aparentemente saud\u00e1veis.<\/p>\n<h3 style=\"text-align: left;\">Leptospirose canina<\/h3>\n<p style=\"text-align: left;\">\u00c9 uma zoonose, ou seja, transmitida de pet para tutor. O cont\u00e1gio \u00e9 pela urina de ratos e os sintomas s\u00e3o des\u00e2nimo, v\u00f4mitos e hemorragias. Pode evoluir para casos cr\u00f4nicos e levar o animal a \u00f3bito.<\/p>\n<p style=\"text-align: left;\">Todas as doen\u00e7as s\u00e3o graves e podem atingir o c\u00e3ozinho antes de 1 ano de idade. Existe a probabilidade de seu pet pegar a doen\u00e7a posteriormente se n\u00e3o for vacinado. Vacinar \u00e9 melhoria e extens\u00e3o da qualidade de vida.<\/p>\n<hr \/>\n<h3>O melhor cuidado \u00e9 a <span style=\"color: #ff6600;\">preven\u00e7\u00e3o!\u00a0<\/span><\/h3>\n<p>Simule um plano de sa\u00fade da Dr Pet para seu pet.<\/p>\n<div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f2850-o1\" lang=\"pt-BR\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/blog\/wp-json\/wp\/v2\/posts\/368#wpcf7-f2850-o1\" method=\"post\" class=\"wpcf7-form init\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"2850\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.6.4\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"pt_BR\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f2850-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/div>\n<p><label> Nome<br \/>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input type=\"text\" name=\"your-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> E-mail<br \/>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input type=\"email\" name=\"your-email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> Telefone<br \/>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input type=\"text\" name=\"your-subject\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> Peso e Idade do pet<br \/>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><input type=\"text\" name=\"your-message\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><input type=\"hidden\" name=\"_wpcf7_captcha_challenge_your-captcha\" value=\"3195883895\" \/><img class=\"wpcf7-form-control wpcf7-captchac wpcf7-captcha-your-captcha\" width=\"72\" height=\"24\" alt=\"captcha\" src=\"https:\/\/blog.doutorpet.com\/blog\/wp-content\/uploads\/wpcf7_captcha\/3195883895.png\" \/><br \/>\n<label>Enter the code: <span class=\"wpcf7-form-control-wrap\" data-name=\"your-captcha\"><input type=\"text\" name=\"your-captcha\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-captchar\" autocomplete=\"off\" aria-invalid=\"false\" \/><\/span><\/label><\/p>\n<p><input type=\"submit\" value=\"Quero simular\" class=\"wpcf7-form-control has-spinner wpcf7-submit\" \/><\/p>\n<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><\/form><\/div>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<p style=\"text-align: left;\">[su_accordion][su_spoiler title=&#8221;Refer\u00eancias:&#8221; open=&#8221;no&#8221; style=&#8221;default&#8221; icon=&#8221;plus&#8221; anchor=&#8221;&#8221; class=&#8221;&#8221;]http:\/\/www.canilmonamourmegan.com.br\/2009\/08\/vacinas-v8-v10-diferencas.html<br \/>\nhttp:\/\/www.cachorrogato.com.br\/cachorros\/vacinacao-caes\/<br \/>\nhttp:\/\/www.cachorrogato.com.br\/cachorros\/cinomose\/[\/su_spoiler][\/su_accordion]\n","protected":false},"excerpt":{"rendered":"<p>As vacinas de V8 e V10, devem ser tomadas em torno de 60 dias de vida do animal, com intervalo de 25 dias entre uma dose e outra. A partir dos 45 dias, o animal pode ser imunizado pela primeira vez. Nas primeiras doses das vacinas V8 e V10, s\u00e3o dadas em 3 \u201cparcelas\u201d, chamadas&#8230;<\/p>\n","protected":false},"author":1,"featured_media":379,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_themeisle_gutenberg_block_has_review":false},"categories":[87,91,1],"tags":[199,581,580,208,578,579,577,226,576,575,235],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Entenda a diferen\u00e7a das vacinas V8 e V10 - Blog Dr Pet<\/title>\n<meta name=\"description\" content=\"A diferen\u00e7a \u00e9 que existem 4 tipos de Leptospirose, para cada tipo existe um ant\u00edgeno espec\u00edfico. A v8 e a v10 protegem o pet contra 7 doen\u00e7as,mas a V8\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.doutorpet.com\/blog\/entenda-a-diferenca-das-vacinas-v8-e-v10\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entenda a diferen\u00e7a das vacinas V8 e V10 - Blog Dr Pet\" \/>\n<meta property=\"og:description\" content=\"A diferen\u00e7a \u00e9 que existem 4 tipos de Leptospirose, para cada tipo existe um ant\u00edgeno espec\u00edfico. A v8 e a v10 protegem o pet contra 7 doen\u00e7as,mas a V8\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.doutorpet.com\/blog\/entenda-a-diferenca-das-vacinas-v8-e-v10\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Dr Pet\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-19T12:41:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-18T18:15:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.doutorpet.com\/blog\/wp-content\/uploads\/2016\/09\/pexels-photo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1279\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dr Pet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dr Pet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/blog.doutorpet.com\/blog\/entenda-a-diferenca-das-vacinas-v8-e-v10\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/blog.doutorpet.com\/blog\/entenda-a-diferenca-das-vacinas-v8-e-v10\/\"},\"author\":{\"name\":\"Dr Pet\",\"@id\":\"https:\/\/blog.doutorpet.com\/blog\/#\/schema\/person\/9ee48669b3c5d8c75090cd4238b8b2bd\"},\"headline\":\"Entenda a diferen\u00e7a das vacinas V8 e V10\",\"datePublished\":\"2016-09-19T12:41:26+00:00\",\"dateModified\":\"2021-02-18T18:15:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/blog.doutorpet.com\/blog\/entenda-a-diferenca-das-vacinas-v8-e-v10\/\"},\"wordCount\":533,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/blog.doutorpet.com\/blog\/#organization\"},\"keywords\":[\"caes\",\"Cinomose\",\"Coronavirose\",\"gatos\",\"Leptospirose canina\",\"Parainfluenza canina\",\"Parvovirose\",\"prevencao\",\"vacina v10\",\"vacina v8\",\"vacinas\"],\"articleSection\":[\"C\u00e3es\",\"Gatos\",\"Sa\u00fade\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/blog.doutorpet.com\/blog\/entenda-a-diferenca-das-vacinas-v8-e-v10\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blog.doutorpet.com\/blog\/entenda-a-diferenca-das-vacinas-v8-e-v10\/\",\"url\":\"https:\/\/blog.doutorpet.com\/blog\/entenda-a-diferenca-das-vacinas-v8-e-v10\/\",\"name\":\"Entenda a diferen\u00e7a das vacinas V8 e V10 - Blog Dr Pet\",\"isPartOf\":{\"@id\":\"https:\/\/blog.doutorpet.com\/blog\/#website\"},\"datePublished\":\"2016-09-19T12:41:26+00:00\",\"dateModified\":\"2021-02-18T18:15:06+00:00\",\"description\":\"A diferen\u00e7a \u00e9 que existem 4 tipos de Leptospirose, para cada tipo existe um ant\u00edgeno espec\u00edfico. A v8 e a v10 protegem o pet contra 7 doen\u00e7as,mas a V8\",\"breadcrumb\":{\"@id\":\"https:\/\/blog.doutorpet.com\/blog\/entenda-a-diferenca-das-vacinas-v8-e-v10\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blog.doutorpet.com\/blog\/entenda-a-diferenca-das-vacinas-v8-e-v10\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.doutorpet.com\/blog\/entenda-a-diferenca-das-vacinas-v8-e-v10\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blog.doutorpet.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"caes\",\"item\":\"https:\/\/blog.doutorpet.com\/blog\/tag\/caes\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Entenda a diferen\u00e7a das vacinas V8 e V10\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.doutorpet.com\/blog\/#website\",\"url\":\"https:\/\/blog.doutorpet.com\/blog\/\",\"name\":\"Blog Dr Pet\",\"description\":\"Dicas para seu melhor amigo!\",\"publisher\":{\"@id\":\"https:\/\/blog.doutorpet.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.doutorpet.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/blog.doutorpet.com\/blog\/#organization\",\"name\":\"Blog Dr Pet\",\"url\":\"https:\/\/blog.doutorpet.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/blog.doutorpet.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.doutorpet.com\/blog\/wp-content\/uploads\/2021\/08\/Logo-Dr-Pet-Jpeg.jpg\",\"contentUrl\":\"https:\/\/www.doutorpet.com\/blog\/wp-content\/uploads\/2021\/08\/Logo-Dr-Pet-Jpeg.jpg\",\"width\":719,\"height\":719,\"caption\":\"Blog Dr Pet\"},\"image\":{\"@id\":\"https:\/\/blog.doutorpet.com\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/blog.doutorpet.com\/blog\/#\/schema\/person\/9ee48669b3c5d8c75090cd4238b8b2bd\",\"name\":\"Dr Pet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/blog.doutorpet.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/68a206f49df0ea34026a9e28de15948c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/68a206f49df0ea34026a9e28de15948c?s=96&d=mm&r=g\",\"caption\":\"Dr Pet\"},\"sameAs\":[\"https:\/\/www.doutorpet.com\"],\"url\":\"https:\/\/blog.doutorpet.com\/blog\/author\/doutorpet\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entenda a diferen\u00e7a das vacinas V8 e V10 - Blog Dr Pet","description":"A diferen\u00e7a \u00e9 que existem 4 tipos de Leptospirose, para cada tipo existe um ant\u00edgeno espec\u00edfico. A v8 e a v10 protegem o pet contra 7 doen\u00e7as,mas a V8","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.doutorpet.com\/blog\/entenda-a-diferenca-das-vacinas-v8-e-v10\/","og_locale":"pt_BR","og_type":"article","og_title":"Entenda a diferen\u00e7a das vacinas V8 e V10 - Blog Dr Pet","og_description":"A diferen\u00e7a \u00e9 que existem 4 tipos de Leptospirose, para cada tipo existe um ant\u00edgeno espec\u00edfico. A v8 e a v10 protegem o pet contra 7 doen\u00e7as,mas a V8","og_url":"https:\/\/blog.doutorpet.com\/blog\/entenda-a-diferenca-das-vacinas-v8-e-v10\/","og_site_name":"Blog Dr Pet","article_published_time":"2016-09-19T12:41:26+00:00","article_modified_time":"2021-02-18T18:15:06+00:00","og_image":[{"width":1920,"height":1279,"url":"https:\/\/blog.doutorpet.com\/blog\/wp-content\/uploads\/2016\/09\/pexels-photo.jpg","type":"image\/jpeg"}],"author":"Dr Pet","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Dr Pet","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.doutorpet.com\/blog\/entenda-a-diferenca-das-vacinas-v8-e-v10\/#article","isPartOf":{"@id":"https:\/\/blog.doutorpet.com\/blog\/entenda-a-diferenca-das-vacinas-v8-e-v10\/"},"author":{"name":"Dr Pet","@id":"https:\/\/blog.doutorpet.com\/blog\/#\/schema\/person\/9ee48669b3c5d8c75090cd4238b8b2bd"},"headline":"Entenda a diferen\u00e7a das vacinas V8 e V10","datePublished":"2016-09-19T12:41:26+00:00","dateModified":"2021-02-18T18:15:06+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.doutorpet.com\/blog\/entenda-a-diferenca-das-vacinas-v8-e-v10\/"},"wordCount":533,"commentCount":1,"publisher":{"@id":"https:\/\/blog.doutorpet.com\/blog\/#organization"},"keywords":["caes","Cinomose","Coronavirose","gatos","Leptospirose canina","Parainfluenza canina","Parvovirose","prevencao","vacina v10","vacina v8","vacinas"],"articleSection":["C\u00e3es","Gatos","Sa\u00fade"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.doutorpet.com\/blog\/entenda-a-diferenca-das-vacinas-v8-e-v10\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.doutorpet.com\/blog\/entenda-a-diferenca-das-vacinas-v8-e-v10\/","url":"https:\/\/blog.doutorpet.com\/blog\/entenda-a-diferenca-das-vacinas-v8-e-v10\/","name":"Entenda a diferen\u00e7a das vacinas V8 e V10 - Blog Dr Pet","isPartOf":{"@id":"https:\/\/blog.doutorpet.com\/blog\/#website"},"datePublished":"2016-09-19T12:41:26+00:00","dateModified":"2021-02-18T18:15:06+00:00","description":"A diferen\u00e7a \u00e9 que existem 4 tipos de Leptospirose, para cada tipo existe um ant\u00edgeno espec\u00edfico. A v8 e a v10 protegem o pet contra 7 doen\u00e7as,mas a V8","breadcrumb":{"@id":"https:\/\/blog.doutorpet.com\/blog\/entenda-a-diferenca-das-vacinas-v8-e-v10\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.doutorpet.com\/blog\/entenda-a-diferenca-das-vacinas-v8-e-v10\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blog.doutorpet.com\/blog\/entenda-a-diferenca-das-vacinas-v8-e-v10\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.doutorpet.com\/blog\/"},{"@type":"ListItem","position":2,"name":"caes","item":"https:\/\/blog.doutorpet.com\/blog\/tag\/caes\/"},{"@type":"ListItem","position":3,"name":"Entenda a diferen\u00e7a das vacinas V8 e V10"}]},{"@type":"WebSite","@id":"https:\/\/blog.doutorpet.com\/blog\/#website","url":"https:\/\/blog.doutorpet.com\/blog\/","name":"Blog Dr Pet","description":"Dicas para seu melhor amigo!","publisher":{"@id":"https:\/\/blog.doutorpet.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.doutorpet.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/blog.doutorpet.com\/blog\/#organization","name":"Blog Dr Pet","url":"https:\/\/blog.doutorpet.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blog.doutorpet.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.doutorpet.com\/blog\/wp-content\/uploads\/2021\/08\/Logo-Dr-Pet-Jpeg.jpg","contentUrl":"https:\/\/www.doutorpet.com\/blog\/wp-content\/uploads\/2021\/08\/Logo-Dr-Pet-Jpeg.jpg","width":719,"height":719,"caption":"Blog Dr Pet"},"image":{"@id":"https:\/\/blog.doutorpet.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.doutorpet.com\/blog\/#\/schema\/person\/9ee48669b3c5d8c75090cd4238b8b2bd","name":"Dr Pet","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blog.doutorpet.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/68a206f49df0ea34026a9e28de15948c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/68a206f49df0ea34026a9e28de15948c?s=96&d=mm&r=g","caption":"Dr Pet"},"sameAs":["https:\/\/www.doutorpet.com"],"url":"https:\/\/blog.doutorpet.com\/blog\/author\/doutorpet\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.doutorpet.com\/blog\/wp-json\/wp\/v2\/posts\/368"}],"collection":[{"href":"https:\/\/blog.doutorpet.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.doutorpet.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.doutorpet.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.doutorpet.com\/blog\/wp-json\/wp\/v2\/comments?post=368"}],"version-history":[{"count":33,"href":"https:\/\/blog.doutorpet.com\/blog\/wp-json\/wp\/v2\/posts\/368\/revisions"}],"predecessor-version":[{"id":6488,"href":"https:\/\/blog.doutorpet.com\/blog\/wp-json\/wp\/v2\/posts\/368\/revisions\/6488"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.doutorpet.com\/blog\/wp-json\/wp\/v2\/media\/379"}],"wp:attachment":[{"href":"https:\/\/blog.doutorpet.com\/blog\/wp-json\/wp\/v2\/media?parent=368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.doutorpet.com\/blog\/wp-json\/wp\/v2\/categories?post=368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.doutorpet.com\/blog\/wp-json\/wp\/v2\/tags?post=368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}